{"id":832,"date":"2023-07-18T15:37:39","date_gmt":"2023-07-18T13:37:39","guid":{"rendered":"https:\/\/www.mocciaterracotte.it\/Store\/?post_type=product&#038;p=832"},"modified":"2023-07-18T15:39:32","modified_gmt":"2023-07-18T13:39:32","slug":"litografia-chiesa-matrice-collegiata-parrocchia-santa-maria-della-colonna-e-san-nicola-di-bari","status":"publish","type":"product","link":"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/prodotto\/litografia-chiesa-matrice-collegiata-parrocchia-santa-maria-della-colonna-e-san-nicola-di-bari\/","title":{"rendered":"Litografia &#8220;Chiesa matrice collegiata parrocchia Santa Maria della Colonna e San Nicola di Bari&#8221;"},"content":{"rendered":"<p>Fotolito su tela ritoccata a mano dall\u2019artista Vito Moccia<\/p>\n<p>Solo tela.<\/p>\n<p>Misura: 25 x 40 cm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fotolito su tela ritoccata a mano dall\u2019artista Vito Moccia Solo tela. Misura: 25 x 40 cm<\/p>\n","protected":false},"featured_media":872,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[25,41],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Litografia &quot;Chiesa matrice collegiata parrocchia Santa Maria della Colonna e San Nicola di Bari&quot; - Fischietti di Terracotta Store<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/prodotto\/litografia-chiesa-matrice-collegiata-parrocchia-santa-maria-della-colonna-e-san-nicola-di-bari\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Litografia &quot;Chiesa matrice collegiata parrocchia Santa Maria della Colonna e San Nicola di Bari&quot; - Fischietti di Terracotta Store\" \/>\r\n<meta property=\"og:description\" content=\"Fotolito su tela ritoccata a mano dall\u2019artista Vito Moccia Solo tela. Misura: 25 x 40 cm\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/prodotto\/litografia-chiesa-matrice-collegiata-parrocchia-santa-maria-della-colonna-e-san-nicola-di-bari\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Fischietti di Terracotta Store\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FischiettiInTerracottaMocciaPagliarulo\/\" \/>\r\n<meta property=\"article:modified_time\" content=\"2023-07-18T13:39:32+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.mocciaterracotte.it\/Store\/wp-content\/uploads\/2023\/07\/LIT1-2-633x1024.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"633\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/prodotto\/litografia-chiesa-matrice-collegiata-parrocchia-santa-maria-della-colonna-e-san-nicola-di-bari\/\",\"url\":\"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/prodotto\/litografia-chiesa-matrice-collegiata-parrocchia-santa-maria-della-colonna-e-san-nicola-di-bari\/\",\"name\":\"Litografia \\\"Chiesa matrice collegiata parrocchia Santa Maria della Colonna e San Nicola di Bari\\\" - Fischietti di Terracotta Store\",\"isPartOf\":{\"@id\":\"https:\/\/www.mocciaterracotte.it\/Store\/#website\"},\"datePublished\":\"2023-07-18T13:37:39+00:00\",\"dateModified\":\"2023-07-18T13:39:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/prodotto\/litografia-chiesa-matrice-collegiata-parrocchia-santa-maria-della-colonna-e-san-nicola-di-bari\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/prodotto\/litografia-chiesa-matrice-collegiata-parrocchia-santa-maria-della-colonna-e-san-nicola-di-bari\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/prodotto\/litografia-chiesa-matrice-collegiata-parrocchia-santa-maria-della-colonna-e-san-nicola-di-bari\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.mocciaterracotte.it\/Store\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Litografia &#8220;Chiesa matrice collegiata parrocchia Santa Maria della Colonna e San Nicola di Bari&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mocciaterracotte.it\/Store\/#website\",\"url\":\"https:\/\/www.mocciaterracotte.it\/Store\/\",\"name\":\"Fischietti di Terracotta Store\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.mocciaterracotte.it\/Store\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mocciaterracotte.it\/Store\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.mocciaterracotte.it\/Store\/#organization\",\"name\":\"Fischietti di Terracotta Store\",\"url\":\"https:\/\/www.mocciaterracotte.it\/Store\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.mocciaterracotte.it\/Store\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.mocciaterracotte.it\/Store\/wp-content\/uploads\/2023\/07\/ffffffff-6.png\",\"contentUrl\":\"https:\/\/www.mocciaterracotte.it\/Store\/wp-content\/uploads\/2023\/07\/ffffffff-6.png\",\"width\":266,\"height\":120,\"caption\":\"Fischietti di Terracotta Store\"},\"image\":{\"@id\":\"https:\/\/www.mocciaterracotte.it\/Store\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FischiettiInTerracottaMocciaPagliarulo\/\",\"https:\/\/www.instagram.com\/mocciaitalianart\/\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Litografia \"Chiesa matrice collegiata parrocchia Santa Maria della Colonna e San Nicola di Bari\" - Fischietti di Terracotta Store","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/prodotto\/litografia-chiesa-matrice-collegiata-parrocchia-santa-maria-della-colonna-e-san-nicola-di-bari\/","og_locale":"it_IT","og_type":"article","og_title":"Litografia \"Chiesa matrice collegiata parrocchia Santa Maria della Colonna e San Nicola di Bari\" - Fischietti di Terracotta Store","og_description":"Fotolito su tela ritoccata a mano dall\u2019artista Vito Moccia Solo tela. Misura: 25 x 40 cm","og_url":"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/prodotto\/litografia-chiesa-matrice-collegiata-parrocchia-santa-maria-della-colonna-e-san-nicola-di-bari\/","og_site_name":"Fischietti di Terracotta Store","article_publisher":"https:\/\/www.facebook.com\/FischiettiInTerracottaMocciaPagliarulo\/","article_modified_time":"2023-07-18T13:39:32+00:00","og_image":[{"width":633,"height":1024,"url":"https:\/\/www.mocciaterracotte.it\/Store\/wp-content\/uploads\/2023\/07\/LIT1-2-633x1024.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/prodotto\/litografia-chiesa-matrice-collegiata-parrocchia-santa-maria-della-colonna-e-san-nicola-di-bari\/","url":"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/prodotto\/litografia-chiesa-matrice-collegiata-parrocchia-santa-maria-della-colonna-e-san-nicola-di-bari\/","name":"Litografia \"Chiesa matrice collegiata parrocchia Santa Maria della Colonna e San Nicola di Bari\" - Fischietti di Terracotta Store","isPartOf":{"@id":"https:\/\/www.mocciaterracotte.it\/Store\/#website"},"datePublished":"2023-07-18T13:37:39+00:00","dateModified":"2023-07-18T13:39:32+00:00","breadcrumb":{"@id":"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/prodotto\/litografia-chiesa-matrice-collegiata-parrocchia-santa-maria-della-colonna-e-san-nicola-di-bari\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mocciaterracotte.it\/Store\/index.php\/prodotto\/litografia-chiesa-matrice-collegiata-parrocchia-santa-maria-della-colonna-e-san-nicola-di-bari\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/prodotto\/litografia-chiesa-matrice-collegiata-parrocchia-santa-maria-della-colonna-e-san-nicola-di-bari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mocciaterracotte.it\/Store\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/negozio\/"},{"@type":"ListItem","position":3,"name":"Litografia &#8220;Chiesa matrice collegiata parrocchia Santa Maria della Colonna e San Nicola di Bari&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.mocciaterracotte.it\/Store\/#website","url":"https:\/\/www.mocciaterracotte.it\/Store\/","name":"Fischietti di Terracotta Store","description":"","publisher":{"@id":"https:\/\/www.mocciaterracotte.it\/Store\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mocciaterracotte.it\/Store\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.mocciaterracotte.it\/Store\/#organization","name":"Fischietti di Terracotta Store","url":"https:\/\/www.mocciaterracotte.it\/Store\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.mocciaterracotte.it\/Store\/#\/schema\/logo\/image\/","url":"https:\/\/www.mocciaterracotte.it\/Store\/wp-content\/uploads\/2023\/07\/ffffffff-6.png","contentUrl":"https:\/\/www.mocciaterracotte.it\/Store\/wp-content\/uploads\/2023\/07\/ffffffff-6.png","width":266,"height":120,"caption":"Fischietti di Terracotta Store"},"image":{"@id":"https:\/\/www.mocciaterracotte.it\/Store\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FischiettiInTerracottaMocciaPagliarulo\/","https:\/\/www.instagram.com\/mocciaitalianart\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/wp-json\/wp\/v2\/product\/832"}],"collection":[{"href":"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/wp-json\/wp\/v2\/comments?post=832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/wp-json\/wp\/v2\/media\/872"}],"wp:attachment":[{"href":"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/wp-json\/wp\/v2\/media?parent=832"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/wp-json\/wp\/v2\/product_cat?post=832"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mocciaterracotte.it\/Store\/index.php\/wp-json\/wp\/v2\/product_tag?post=832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}